{"id":4404,"date":"2026-05-29T11:01:29","date_gmt":"2026-05-29T08:01:29","guid":{"rendered":"https:\/\/merinannies.com\/informations-utiles\/"},"modified":"2026-07-04T17:35:41","modified_gmt":"2026-07-04T14:35:41","slug":"informations-utiles","status":"publish","type":"page","link":"https:\/\/merinannies.com\/fr\/informations-utiles\/","title":{"rendered":"Informations utiles"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1499414717989{background-image: url(http:\/\/merinannies.immko.gr\/wp-content\/uploads\/2017\/06\/bg-style-1.png?id=434) !important;background-position: 0 0 !important;background-repeat: no-repeat !important;}\u00a0\u00bb][vc_column][vc_empty_space height=\u00a0\u00bb1.5em\u00a0\u00bb alter_height=\u00a0\u00bbnone\u00a0\u00bb hide_on_mobile=\u00a0\u00bb1&Prime;][vc_empty_space height=\u00a0\u00bb5em\u00a0\u00bb alter_height=\u00a0\u00bbnone\u00a0\u00bb hide_on_mobile=\u00a0\u00bb\u00a0\u00bb]<div  id=\"sc_action_1391250335\" \n\tclass=\"sc_action color_style_default sc_action_default\"><h6 class=\"sc_item_subtitle sc_action_subtitle sc_align_center sc_item_title_style_default\">Useful Info<\/h6><div class=\"sc_item_descr sc_action_descr sc_align_center\"><p>Les vacances au ski sont avant tout l\u2019occasion de profiter de la montagne, quel que soit votre niveau. Chez Merinannies, nous mettons tout en \u0153uvre pour rendre votre s\u00e9jour aussi agr\u00e9able que possible. Voici quelques conseils pratiques pour vous aider \u00e0 pr\u00e9parer vos vacances.<\/p>\n<\/div><div class=\"sc_action_content sc_item_content\"><div class=\"sc_action_item sc_action_item_default sc_action_item_mc\">\n\t\t\t<\/div><\/div><\/div><!-- \/.sc_action -->[vc_empty_space height=\u00a0\u00bb1.5em\u00a0\u00bb alter_height=\u00a0\u00bbnone\u00a0\u00bb hide_on_mobile=\u00a0\u00bb1&Prime;][vc_empty_space height=\u00a0\u00bb5em\u00a0\u00bb alter_height=\u00a0\u00bbnone\u00a0\u00bb hide_on_mobile=\u00a0\u00bb\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row_content_no_spaces\u00a0\u00bb][vc_column]<div id=\"sc_line_1240364446\"\n\t\tclass=\"sc_line var_2 color_5 top\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 1902.6 75\" style=\"enable-background:new 0 0 1902.6 75;\" xml:space=\"preserve\">\n<path class=\"color_1\" d=\"M221.9,75c2.5-3.6,4.9-7.2,7.4-10.8c-2.3,0.5-4.5,1.1-6.8,1.6c11.5-2.7,29.6-6.8,52.2-10.7c40-7,68.4-9.2,131.8-14.8\n\tc48.2-4.3,72.3-6.4,82.1-7.4C607.5,20.5,664.8,2.5,756.7,0c22.4-0.6,41.4-0.1,44.1,0c39.5,1.1,69.4,4.8,103.2,8.9\n\tc9,1.1,32.5,4.1,61,8.9c7.2,1.2,14.6,2.5,22.6,4c13.9,2.6,26.7,5.3,38.2,7.8c29.2,6.4,52.4,12.6,54.8,13.2\n\tc24.5,6.4,94.4,16.4,277.1,32.2c-192,1.8-384,2.6-576,2.6C595,77.6,408.5,76.7,221.9,75z\"\/>\n<path class=\"color_2\" d=\"M0,75c0-13,0-26,0-39c48.9-8.3,122.7-17.7,212.9-16.4c61.1,0.9,121.6,9.9,243,24.1c114.5,13.4,179,21,241.4,25\n\tc70.7,4.5,136.7,4.4,358.6-13c309.9-24.3,307.6-33.9,412.5-36.1c102.8-2.2,251.5,3.9,434.2,45.1c0,3.4,0,6.9,0,10.3\n\tc-608.1,0-1216.3,0-1824.4,0C52.1,75,26,75,0,75z\"\/>\n<\/svg><\/div>[\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1535460771593{padding-top: 20px !important;padding-bottom: 20px !important;background: #f9f9f9 url(http:\/\/merinannies.immko.gr\/wp-content\/uploads\/2017\/06\/bg-style-1.png?id=434) !important;background-position: 0 0 !important;background-repeat: no-repeat !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; el_class=\u00a0\u00bbsc_title color_style_default sc_title_extra go-center\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbAvant votre arriv\u00e9e\u00a0\u00bb font_container=\u00a0\u00bbtag:h3|text_align:left\u00a0\u00bb el_class=\u00a0\u00bbsc_item_subtitle sc_title_subtitle sc_align_center sc_item_title_style_extra\u00a0\u00bb][vc_wp_text el_class=\u00a0\u00bbjustify\u00a0\u00bb]D\u00e8s que votre r\u00e9servation sera confirm\u00e9e, nous vous demanderons de remplir un formulaire avec les informations les plus importantes concernant le d\u00e9roulement de la journ\u00e9e de votre enfant, ses besoins alimentaires sp\u00e9cifiques, ses cours de ski et tout ce qui vous semble important pour son bien- \u00eatre lors de votre s\u00e9jour.<br \/>Nous vous conseillons \u00e9galement un appel vid\u00e9o avec votre nounou\u00a0 afin que votre enfant puisse se familiariser avec elle et que vous puissiez poser toutes vos questions.<\/p>\n<p><strong>Que faut- il emmener<br \/>\n<\/strong>Comme \u00e9quipement de base nous recommandons des chaussures d\u00b4int\u00e9rieur et d\u00b4ext\u00e9rieur, une veste imperm\u00e9able pour les activit\u00e9s en plein air, ainsi que des bottes robustes pour la neige. Il faut \u00e9galement pr\u00e9voir des bonnets, des gants et des \u00e9charpes chauds, de la protection solaire ainsi que des lunettes de soleil ou de ski (aussi pour les b\u00e9b\u00e9s).<br \/>Sur place vous trouverez bien s\u00fbr des supermarch\u00e9s o\u00f9 vous pourrez acheter tout ce dont vous avez besoin. Nous vous proposons \u00e9galement de l\u00b4aide pour organiser vos courses. G\u00e9n\u00e9ralement , des jouets, des livres ou DVDs sont disponibles dans votre chalet r\u00e9serv\u00e9. N\u00e9anmoins nous vous recommandons d\u00b4apporter les objets pr\u00e9f\u00e9r\u00e9s de votre enfants comme un doudou, un livret et son gobelet de c\u0153ur. Nous nous occuperons par contre de notre c\u00f4t\u00e9 d\u00b4apporter tout le mat\u00e9riel de loisirs cr\u00e9atifs, de bricolage ou de dessin. Veuillez-vous renseigner avant votre arriv\u00e9e aupr\u00e8s du gestionnaire du chalet sur l\u00b4\u00e9quipement disponible pour les b\u00e9b\u00e9s et les enfants, notamment des chaises hautes, des lits de b\u00e9b\u00e9 et des poussettes. S\u00b4il vous plait, informez le personnel de votre chalet\/h\u00f4tel que vous avez engag\u00e9 une nounou. Si elle sera responsable de pr\u00e9parer le d\u00e9jeuner, vous devrez v\u00e9rifier si l\u00b4utilisation de la cuisine du chalet\/ de l\u00b4h\u00f4tel est autoris\u00e9e.[\/vc_wp_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb5022&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb style=\u00a0\u00bbvc_box_shadow_3d\u00a0\u00bb onclick=\u00a0\u00bbzoom\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1697027006009{padding-top: 40px !important;}\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1697027330301{padding-top: 40px !important;padding-bottom: 40px !important;background-color: #ededed !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; el_class=\u00a0\u00bbsc_title color_style_default sc_title_extra go-center\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbArriv\u00e9e\u00a0\u00bb font_container=\u00a0\u00bbtag:h3|text_align:left\u00a0\u00bb el_class=\u00a0\u00bbsc_item_subtitle sc_title_subtitle sc_align_center sc_item_title_style_extra\u00a0\u00bb][vc_column_text]<br \/>\nLe premier\u00a0 jour de la garde, votre nounou arrivera environ 20 minutes plus t\u00f4t, pour vous rencontrer et discuter avec vous des besoins sp\u00e9cifiques.<br \/>Votre nounou conservera un r\u00e9capitulatif des besoins de soins, des cours de ski et de toutes les autres informations importantes. Si vos enfants auront besoins de prendre des m\u00e9dicaments, il est indispensable de signer une autorisation pour ceci \u00e0 la nounou. Veillez \u00e0 montrer \u00e0 votre nounou o\u00f9 se trouvent les m\u00e9dicaments, les couches et tous les autres \u00e9quipements n\u00e9cessaires.<br \/>Si il y a des autres besoins m\u00e9dicaux ou sp\u00e9cifiques, ceux-ci doivent \u00eatre convenus directement avec votre nounou.<br \/>Vous \u00eates invit\u00e9s \u00e0 \u00e9changer des informations actuelles ainsi que des photos lors de votre s\u00e9jour avec votre nounou \u00e0 travers WhatsApp.<\/p>\n<p><strong>En cas de maladie<br \/>\n<\/strong>Si votre enfant est atteint d\u00b4une maladie contagieuse, nous pouvons pas garantir sa prise en charge. Bien s\u00fbr des rhumes et toux classiques en sont exclus.<\/p>\n<p><strong>Comportement<br \/>\n<\/strong>Nous encourageons un comportement positif. Tout comportement inappropri\u00e9 ou dangereux ne sera pas tol\u00e9r\u00e9 et va devoir \u00eatre discut\u00e9 avec vous imm\u00e9diatement.<\/p>\n<p><strong>\u00a0<\/strong><br \/>\n[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb5023&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb style=\u00a0\u00bbvc_box_shadow_3d\u00a0\u00bb onclick=\u00a0\u00bbzoom\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1697027342087{padding-top: 40px !important;padding-bottom: 100px !important;background-color: #f9f9f9 !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; el_class=\u00a0\u00bbsc_title color_style_default sc_title_extra go-center\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbPendant votre s\u00e9jour\u00a0\u00bb font_container=\u00a0\u00bbtag:h3|text_align:left\u00a0\u00bb el_class=\u00a0\u00bbsc_item_subtitle sc_title_subtitle sc_align_center sc_item_title_style_extra\u00a0\u00bb][vc_column_text]<br \/>\n<strong>Activit\u00e9s et animations<br \/>\n<\/strong>Avec votre accord explicite, nos nounous accompagnent vos enfants en pleine nature pour des exp\u00e9riences en plein air soigneusement s\u00e9lectionn\u00e9es, telles que des promenades, des balades en luge, des visites de terrains de jeux (favoriser le contact avec d\u00b4autres enfants), des concours de bonhommes de neige, des explorations dans la for\u00eat, des chasses au tr\u00e9sor et des jeux de cache-cache, des joyeuses batailles de boule de neige, des trajets en t\u00e9l\u00e9cabine et des pauses chocolat chaud.<br \/>\u00c0 l\u00b4int\u00e9rieur nos nounous vont pouvoir proposer des activit\u00e9s cr\u00e9atives comme le bricolage, le dessin, la peinture, la construction, chanter et danser, faire des g\u00e2teaux, jouer des jeux de r\u00f4les, d\u00e9couvrir des bo\u00eetes \u00e0 tr\u00e9sor\u00a0 et des cartes de m\u00e9t\u00e9o, \u00e9crire des lettres et cartes pour les amis et la famille, lire des histoires ou se relaxer aupr\u00e8s d\u00b4un film sympa. Si vous souhaitez prendre le d\u00eener ou un ap\u00e9ro \u00e0 l\u00b4ext\u00e9rieur nous vous proposons un accompagnement exclusif pour les activit\u00e9s du soir de vos enfants.<br \/>Nous pouvons emmener les enfants \u00e0 la patinoire, \u00e1 la salle de bowling, \u00e1 la piscine, faire une petite balade \u00e0 travers la ville ou tout simplement jouer \u00e0 l\u00b4int\u00e9rieur. Il est possible de trouver tous ces genres d\u00b4activit\u00e9s dans toutes les stations, nous vous conseillerons avec plaisir \u00e0 ce sujet.<\/p>\n<p><strong>D\u00e9jeuner et Go\u00fbter<br \/>\n<\/strong>Les repas peuvent \u00eatre pr\u00e9par\u00e9s par la nounous d\u00b4apr\u00e8s les instructions des parents et en suivant les conseil d\u00b4utilisation de la cuisine du chalet.<br \/>Pour le tous petits il est recommand\u00e9 d\u00b4emmener la poudre de lait habituelle de votre pays de r\u00e9sidence car il se peut que vous ne trouveriez pas la marque de votre choix dans certaines stations. Evidemment vous pourrez acheter toutes sortes de couches dans toutes les stations et n\u00b4aurez pas besoin d\u00b4en emmener. En tous les cas votre nounou sera dispos\u00e9e \u00e0 vous aider pour faire des achats en cas de besoin.<\/p>\n<p>&nbsp;<br \/>\n[\/vc_column_text][vc_custom_heading text=\u00a0\u00bbFAQ\u00a0\u00bb font_container=\u00a0\u00bbtag:h3|text_align:left\u00a0\u00bb el_class=\u00a0\u00bbsc_item_subtitle sc_title_subtitle sc_align_center sc_item_title_style_extra\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1697028562102{margin-top: 60px !important;}\u00a0\u00bb][vc_toggle title=\u00a0\u00bbQue peuvent faire les parents afin de garantir que tout se d\u00e9roule parfaitement avant leur arriv\u00e9e \u00e0 la station?\u00a0\u00bb style=\u00a0\u00bbround_outline\u00a0\u00bb color=\u00a0\u00bbblue\u00a0\u00bb size=\u00a0\u00bblg\u00a0\u00bb custom_font_container=\u00a0\u00bbtag:h5|font_size:20|text_align:left\u00a0\u00bb custom_google_fonts=\u00a0\u00bbfont_family:Metrophobic%3Aregular|font_style:400%20regular%3A400%3Anormal\u00a0\u00bb use_custom_heading=\u00a0\u00bbtrue\u00a0\u00bb]<br \/>\nLisez avec votre enfant certains de ses livres pr\u00e9f\u00e9r\u00e9s sur la neige afin qu\u2019 il puisse d\u00e9couvrir de mani\u00e8re agr\u00e9able ce qu\u2019 il l \u00b4attendra en montagne.<br \/>Vous pouvez lui montrer des images des paysages enneig\u00e9s avec les animaux qui y habitent et lui expliquer qu\u00b4il pourra m\u00eame observer ses propres empreintes dans la neige.<br \/>Si vous voyagez pendant les vacances de no\u00ebl, il y aura s\u00fbrement une visite du p\u00e8re no\u00ebl, et dans la p\u00e9riode de P\u00e2ques votre nounou pourra organiser une chasse aux \u0153ufs de P\u00e2ques.<br \/>Emmener certains de ses livres, jouets et jeux pr\u00e9f\u00e9r\u00e9s va faire sentir votre enfant tr\u00e8s vite \u00e0 l\u00b4aise.<br \/>Finalement nous recommandons un appel vid\u00e9o avec votre nounou pour que votre enfant puisse avoir un premier contact, se sentir rassur\u00e9 et gagner confiance d\u00e8s le premier \u00e9change.<br \/>\n[\/vc_toggle][vc_toggle title=\u00a0\u00bbComment garantissons-nous que les enfants puissent interagir avec d\u2019autres enfants alors que nos services sont propos\u00e9s de mani\u00e8re priv\u00e9e?\u00a0\u00bb style=\u00a0\u00bbround_outline\u00a0\u00bb color=\u00a0\u00bbblue\u00a0\u00bb size=\u00a0\u00bblg\u00a0\u00bb custom_font_container=\u00a0\u00bbtag:h5|font_size:20|text_align:left\u00a0\u00bb custom_google_fonts=\u00a0\u00bbfont_family:Metrophobic%3Aregular|font_style:400%20regular%3A400%3Anormal\u00a0\u00bb use_custom_heading=\u00a0\u00bbtrue\u00a0\u00bb]<br \/>\nVous pouvez en discuter directement avec votre nounou qui va assurer de visiter des endroits o\u00f9 vos enfants pourront jouer avec d\u00b4autres enfants, que \u00e7a soit \u00e0 la m\u00e9diath\u00e8que, aux terrains de jeu ou ailleurs.<br \/>\n[\/vc_toggle][vc_toggle title=\u00a0\u00bbComment g\u00e9rons-nous les situations o\u00f9 un enfant se sent triste ou contrari\u00e9 au moment o\u00f9 ses parents vont partir ?\u00a0\u00bb style=\u00a0\u00bbround_outline\u00a0\u00bb color=\u00a0\u00bbblue\u00a0\u00bb size=\u00a0\u00bblg\u00a0\u00bb custom_font_container=\u00a0\u00bbtag:h5|font_size:20|text_align:left\u00a0\u00bb custom_google_fonts=\u00a0\u00bbfont_family:Metrophobic%3Aregular|font_style:400%20regular%3A400%3Anormal\u00a0\u00bb use_custom_heading=\u00a0\u00bbtrue\u00a0\u00bb]<br \/>\nSi votre enfant se sent contrari\u00e9\u00a0 nous allons toujours essayer de l\u00b4orienter avec douceur vers ses activit\u00e9s pr\u00e9f\u00e9r\u00e9es.<br \/>Si l\u00b4enfant n\u00b4a pas de soucis de sant\u00e9 \u00e7a ne dure g\u00e9n\u00e9ralement pas longtemps jusqu\u00b4\u00e0 ce qu\u00b4il puisse pleinement profiter du moment avec la nounou. Aussi de sortir avec les enfants \u00e0 des endroits sp\u00e9cialement adapt\u00e9s aux petits va garantir un moment joyeux sans les parents.<br \/>\n[\/vc_toggle][vc_toggle title=\u00a0\u00bbPrise en compte des besoins alimentaires sp\u00e9cifiques ?\u00a0\u00bb style=\u00a0\u00bbround_outline\u00a0\u00bb color=\u00a0\u00bbblue\u00a0\u00bb size=\u00a0\u00bblg\u00a0\u00bb custom_font_container=\u00a0\u00bbtag:h5|font_size:20|text_align:left\u00a0\u00bb custom_google_fonts=\u00a0\u00bbfont_family:Metrophobic%3Aregular|font_style:400%20regular%3A400%3Anormal\u00a0\u00bb use_custom_heading=\u00a0\u00bbtrue\u00a0\u00bb]<br \/>\nPour \u00eatre le mieux pr\u00e9par\u00e9 \u00e0 des \u00e9ventuels besoins sp\u00e9cifiques concernant\u00a0 \u00b4alimentation, nous vous prions de nous fournir ces informations en amont \u00e0 travers le formulaire que nous vous mettons \u00e0 disposition. Le g\u00e9rant du chalet ou le personnel de l\u00b4h\u00f4tel ou vous logerez s\u00b4occupera \u00e9galement de vous proposer des repas adapt\u00e9s \u00e0 vos besoins. Id\u00e9alement vous vous renseignez \u00e0 ce sujet avant votre arriv\u00e9e.<br \/>\n[\/vc_toggle][vc_toggle title=\u00a0\u00bbEst-il possible pour vos nounous d\u2019assurer le transfert des enfants vers l\u2019\u00e9cole de ski ainsi que leur retour ?\u00a0\u00bb style=\u00a0\u00bbround_outline\u00a0\u00bb color=\u00a0\u00bbblue\u00a0\u00bb size=\u00a0\u00bblg\u00a0\u00bb custom_font_container=\u00a0\u00bbtag:h5|font_size:20|text_align:left\u00a0\u00bb custom_google_fonts=\u00a0\u00bbfont_family:Metrophobic%3Aregular|font_style:400%20regular%3A400%3Anormal\u00a0\u00bb use_custom_heading=\u00a0\u00bbtrue\u00a0\u00bb]<br \/>\nOui, avec votre autorisation explicite ceci fait partie des responsabilit\u00e9s des nounous.<br \/>Pour garantir un d\u00e9roulement fluide, veuillez nous fournir d\u00b4avance les informations concernant l\u00b4endroit pr\u00e9cis du cours de ski, le nom et le num\u00e9ro de t\u00e9l\u00e9phone du moniteur de ski ainsi que l\u00b4\u00e9cole de ski.<\/p>\n<p>G\u00e9n\u00e9ralement, le retour jusqu\u00b4au chalet ou \u00e0 l\u00b4h\u00f4tel \u00a0du cours de ski se fait en bus avec la nounou, \u00e0 moins qu\u00b4un autre moyen de transport priv\u00e9 n\u00b4ait \u00e9t\u00e9 organis\u00e9. Surtout si la prise en charge concerne plus que 2 enfants, tenez \u00e0 assurer que les enfants soient capables de porter leur mat\u00e9riel de ski eux-m\u00eames bien que la nounou les aidera bien \u00e9videmment de son mieux possible.<br \/>\n[\/vc_toggle][vc_toggle title=\u00a0\u00bbEst- il possible que la nounou accompagne les enfants lors des cours de ski et d\u00b4autres activit\u00e9s de sport d\u00b4hiver ?\u00a0\u00bb style=\u00a0\u00bbround_outline\u00a0\u00bb color=\u00a0\u00bbblue\u00a0\u00bb size=\u00a0\u00bblg\u00a0\u00bb custom_font_container=\u00a0\u00bbtag:h5|font_size:20|text_align:left\u00a0\u00bb custom_google_fonts=\u00a0\u00bbfont_family:Metrophobic%3Aregular|font_style:400%20regular%3A400%3Anormal\u00a0\u00bb use_custom_heading=\u00a0\u00bbtrue\u00a0\u00bb]<br \/>\nAvant tout, nos nounous assurent leur travail de garde d \u00b4enfants et ne sont pas des moniteurs de ski. Toutefois elles peuvent \u00eatre \u00e0 proximit\u00e9 lors des cours de ski et , si n\u00e9cessaire intervenir de mani\u00e8re douce et bienveillante pour motiver votre enfant \u00e0 poursuivre le cours de ski. Si il est n\u00e9cessaire elle peut aussi le retirer un moment du cours, si votre enfants ne se sont pas \u00e0 l\u00b4aise pour une raison ou une autre.<br \/>Si vous l\u00b4autorisez, un accompagnement lors d\u2019autres activit\u00e9s de sports d\u2019hiver est \u00e9galement possible.<br \/>\n[\/vc_toggle][vc_toggle title=\u00a0\u00bbQuel est le mode de communication entre les parents et la nounou que nous recommandons au cours de la journ\u00e9e ?\u00a0\u00bb style=\u00a0\u00bbround_outline\u00a0\u00bb color=\u00a0\u00bbblue\u00a0\u00bb size=\u00a0\u00bblg\u00a0\u00bb custom_font_container=\u00a0\u00bbtag:h5|font_size:20|text_align:left\u00a0\u00bb custom_google_fonts=\u00a0\u00bbfont_family:Metrophobic%3Aregular|font_style:400%20regular%3A400%3Anormal\u00a0\u00bb use_custom_heading=\u00a0\u00bbtrue\u00a0\u00bb]<br \/>\nG\u00e9n\u00e9ralement la nounou va utiliser WhatsApp pour vous communiquer\u00a0 sur le bien-\u00eatre de vos enfants durant la journ\u00e9e ou bien pour partager des photos. Elle va le faire de mani\u00e8re discr\u00e8te si vous l\u00b4avez demand\u00e9 de le faire car elle ne voudra pas vous d\u00e9ranger pendant votre temps de repos.<br \/>\n[\/vc_toggle][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb5024&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb style=\u00a0\u00bbvc_box_shadow_3d\u00a0\u00bb onclick=\u00a0\u00bbzoom\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"sc_layouts sc_layouts_default sc_layouts_191\">[vc_row full_width=\"stretch_row_content_no_spaces\" css_animation=\"flipInX\"][vc_column icons_position=\"left\"]<div class=\"sc_layouts_item\"><div id=\"sc_line_2111323895\"\n\t\tclass=\"sc_line var_1 color_2 top\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 1902.8 75\" style=\"enable-background:new 0 0 1902.8 75;\" xml:space=\"preserve\">\n<path class=\"color_1\" d=\"M787.4,59.4c72.4,5.3,129.4-1.6,168.6-9.1c57-10.9,83.9-24.6,157.2-36.5c47.1-7.7,82.6-9.6,114.3-11.3\n\tc28.7-1.5,140.3-6.4,291.4,14.8c59.9,8.4,136.8,22.4,225,47c-318.9,3.6-637.7,7.1-956.6,10.7C787.4,69.8,787.4,64.6,787.4,59.4z\"\/>\n<path class=\"color_2\" d=\"M0,40.7c75.6-10.6,140.6-17.1,191.5-21.3c45.5-3.8,92.8-7.6,156.5-9c47.3-1,82.6-0.3,141,1c58.5,1.3,87.8,1.9,128,5\n\tc58.2,4.5,105.8,11.2,118,13c42.8,6.2,54.5,9.4,98,15c30.3,3.9,55.1,6.2,84.5,8.7c112.8,9.3,192.2,15.9,297.5,16\n\tc57.3,0.1,110.6-1.8,132.7-2.6c9.2-0.3,11.3-0.4,110.3-4.9c73.5-3.3,79.6-3.6,92.3-4.5c54.9-4,94.7-10.2,116.7-13.5\n\tc49-7.3,124.4-16.9,236.3-26.2c-0.2,19.2-0.3,38.4-0.5,57.7C1268.5,75,634.3,75,0,75C0,63.6,0,52.1,0,40.7z\"\/>\n<\/svg><\/div><\/div>[\/vc_column][\/vc_row][vc_row full_width=\"stretch_row\" content_placement=\"bottom\" css_animation=\"flipInX\" css=\".vc_custom_1537277199015{background-color: #ffd786 !important;}\" el_class=\"extra-action\"][vc_column icons_position=\"left\"][vc_empty_space height=\"3em\" alter_height=\"none\" hide_on_mobile=\"\"][vc_row_inner content_placement=\"bottom\"][vc_column_inner width=\"2\/3\" icons_position=\"left\"]<div class=\"sc_layouts_item\"><div id=\"sc_title_1255412645\"\n\t\tclass=\"sc_title color_style_default scheme_dark sc_title_default go-left\"><h6 class=\"sc_item_subtitle sc_title_subtitle sc_align_left sc_item_title_style_default\">book your nanny now<\/h6><\/div><!-- \/.sc_title --><\/div>[vc_empty_space height=\"1.5em\" alter_height=\"none\" hide_on_mobile=\"\"][vc_empty_space height=\"1.5em\" alter_height=\"none\" hide_on_mobile=\"1\"][\/vc_column_inner][vc_column_inner width=\"1\/3\" icons_position=\"left\"]<div class=\"sc_layouts_item\"><div class=\"sc_item_button sc_button_wrap sc_align_right\"><a href=\"\/book-page\" id=\"sc_button_265906290\" class=\"sc_button color_style_dark sc_button_default sc_button_size_normal sc_button_icon_left\"><span class=\"sc_button_text\"><span class=\"sc_button_title\">Discover More<\/span><\/span><!-- \/.sc_button_text --><\/a><!-- \/.sc_button --><\/div><!-- \/.sc_item_button --><\/div>[vc_empty_space height=\"2.3em\" alter_height=\"none\" hide_on_mobile=\"1\"][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\"3em\" alter_height=\"none\" hide_on_mobile=\"\"][\/vc_column][\/vc_row]<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1499414717989{background-image: url(<a href=\"http:\/\/merinannies.immko.gr\/wp-content\/uploads\/2017\/06\/bg-style-1.png?id=434)\" target=\"_blank\">http:\/\/merinannies.immko.gr\/wp-content\/uploads\/2017\/06\/bg-style-1.png?id=434)<\/a> !important;background-position: 0 0 !important;background-repeat: no-repeat !important;}\u00a0\u00bb][vc_column][vc_empty_space height=\u00a0\u00bb1.5em\u00a0\u00bb alter_height=\u00a0\u00bbnone\u00a0\u00bb hide_on_mobile=\u00a0\u00bb1&Prime;][vc_empty_space height=\u00a0\u00bb5em\u00a0\u00bb alter_height=\u00a0\u00bbnone\u00a0\u00bb hide_on_mobile=\u00a0\u00bb\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb1.5em\u00a0\u00bb alter_height=\u00a0\u00bbnone\u00a0\u00bb hide_on_mobile=\u00a0\u00bb1&Prime;][vc_empty_space height=\u00a0\u00bb5em\u00a0\u00bb alter_height=\u00a0\u00bbnone\u00a0\u00bb hide_on_mobile=\u00a0\u00bb\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row_content_no_spaces\u00a0\u00bb][vc_column][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1535460771593{padding-top: 20px !important;padding-bottom: 20px !important;background: #f9f9f9 url(<a href=\"http:\/\/merinannies.immko.gr\/wp-content\/uploads\/2017\/06\/bg-style-1.png?id=434)\" target=\"_blank\">http:\/\/merinannies.immko.gr\/wp-content\/uploads\/2017\/06\/bg-style-1.png?id=434)<\/a> !important;background-position: 0 0 !important;background-repeat: no-repeat !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; el_class=\u00a0\u00bbsc_title color_style_default sc_title_extra go-center\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbAvant votre arriv\u00e9e\u00a0\u00bb&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4404","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/merinannies.com\/fr\/wp-json\/wp\/v2\/pages\/4404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/merinannies.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/merinannies.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/merinannies.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/merinannies.com\/fr\/wp-json\/wp\/v2\/comments?post=4404"}],"version-history":[{"count":9,"href":"https:\/\/merinannies.com\/fr\/wp-json\/wp\/v2\/pages\/4404\/revisions"}],"predecessor-version":[{"id":5028,"href":"https:\/\/merinannies.com\/fr\/wp-json\/wp\/v2\/pages\/4404\/revisions\/5028"}],"wp:attachment":[{"href":"https:\/\/merinannies.com\/fr\/wp-json\/wp\/v2\/media?parent=4404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}